{"id":10263,"date":"2022-10-04T11:35:00","date_gmt":"2022-10-04T09:35:00","guid":{"rendered":"https:\/\/isob-regensburg.net\/?p=10263"},"modified":"2023-05-02T15:44:25","modified_gmt":"2023-05-02T13:44:25","slug":"training-im-ihilead-projekt-in-granada-spanien","status":"publish","type":"post","link":"https:\/\/isob-regensburg.net\/en\/evaluationsauftrag\/training-im-ihilead-projekt-in-granada-spanien\/","title":{"rendered":"Training im iHiLead Projekt in Granada, Spanien"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Das Konsortium der sieben vom Ministerium f\u00fcr Bildung und Kultur unterst\u00fctzten indonesischen Universit\u00e4ten und die drei europ\u00e4ischen Partneruniversit\u00e4ten veranstalteten im Rahmen des iHiLead (Indonesian Higher Education Leadership) Projekts vom 26. bis 30. September 2022 an der Universit\u00e4t Granada einen Workshop zur Schulung des Personals der indonesischen Partner. Das Projekt m\u00f6chte Mitarbeitende in F\u00fchrungspositionen indonesischer Hochschulen in ihren F\u00fchrungskompetenzen weiterbilden, da die Herausforderungen der Hochschulbildung in der VUCA-\u00c4ra Schnelligkeit, Flexibilit\u00e4t und Genauigkeit bei der Entscheidungsfindung erfordern. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die teilnehmenden Universit\u00e4ten sind die Brawijaya Universit\u00e4t, die UII, die Ahmad Dahlan Universit\u00e4t (UAD), die President Universit\u00e4t, die Semarang Staatsuniversit\u00e4t, die Padjajaran Universit\u00e4t und die STIE Malangkucecwara sowie die drei europ\u00e4ischen Universit\u00e4ten, die Universit\u00e4t von Gloucestershire, England, die Universit\u00e4t Granada Spanien und die International School for Social and Business Studies Slowenien. Die Er\u00f6ffnungsrede der Veranstaltung hielten Dr. Irene Pedreira Romero, Direktorin f\u00fcr Projekte und internationale Vereinbarungen und Vertreterin des Rektors der Universit\u00e4t Granada, Dr. Tjitjik Srie Tjahjandarie vom Ministerium f\u00fcr Bildung und Kultur, Dr. Francisco Javier Montoro R\u00edos, Leiter des Zentrums f\u00fcr moderne Sprachen in Granada, David Dawson, Hauptkoordinator des Projekts an der Universit\u00e4t von Gloucestershire und Ir. Ilya Fadjar Maharika, Ph.D. Projektkoordinator von der Islamischen Universit\u00e4t Indonesien. Die Seminare an der Universit\u00e4t von Granada waren sehr gut besucht. Bei diesen handelt es sich unter anderem um David Dawsons EU-Best-Practice-Seminar zu &#8222;Principles for Creating Impact from Higher Education&#8220; und das Seminar &#8222;Creating Policy Impact &#8211; The Experience from University of Granada&#8220;, gehalten von Dr. Jos\u00e9 Alberto Casta\u00f1eda-Garc\u00eda, Vizedekan f\u00fcr Forschung und Postgraduiertenstudien der Fakult\u00e4t f\u00fcr Wirtschaftswissenschaften. Dar\u00fcber hinaus lieferten David Dawson, Valerij Dermol und Rodrigo Martin-Rojas Beispiele f\u00fcr wirkungsvolle Projekte im Hochschulbereich. Dieses Projekt ist von gro\u00dfer strategischer Bedeutung und wird voraussichtlich einen erheblichen Einfluss auf die Verbesserung der Qualit\u00e4t der Hochschuleinrichtungen in Indonesien haben und die Verwirklichung des MBKM-Programms (Merdeka Belajar Kampus Merdeka) unterst\u00fctzen. Einige Materialien wie authentische F\u00fchrung, Ressourcenmanagement, Konfliktmanagement sowie mehrere Fallbesprechungen dienten der Wissensvermittlung. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ISOB \u00fcbernimmt als externe Evaluationsinstanz die interne Qualit\u00e4tssicherung und unterst\u00fctzt die Selbstevaluation des Projektteams. <a href=\"https:\/\/ihilead.id\/\">Click here<\/a> geht es zur Projektwebseite.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/isob-regensburg.net\/wp-content\/uploads\/2023\/03\/4.-oktober-2022.jpeg\" alt=\"\" class=\"wp-image-10264\" width=\"800\" height=\"600\" srcset=\"https:\/\/isob-regensburg.net\/wp-content\/uploads\/2023\/03\/4.-oktober-2022.jpeg 1600w, https:\/\/isob-regensburg.net\/wp-content\/uploads\/2023\/03\/4.-oktober-2022-768x576.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Das Konsortium der sieben vom Ministerium f\u00fcr Bildung und Kultur unterst\u00fctzten indonesischen Universit\u00e4ten und die drei europ\u00e4ischen Partneruniversit\u00e4ten veranstalteten im Rahmen des iHiLead (Indonesian Higher Education Leadership) Projekts vom 26. bis 30. September 2022 an der Universit\u00e4t Granada einen Workshop zur Schulung des Personals der indonesischen Partner. Das Projekt m\u00f6chte Mitarbeitende in F\u00fchrungspositionen indonesischer Hochschulen in ihren F\u00fchrungskompetenzen weiterbilden, da die Herausforderungen der Hochschulbildung in der VUCA-\u00c4ra Schnelligkeit, Flexibilit\u00e4t und Genauigkeit bei der Entscheidungsfindung erfordern. Die teilnehmenden Universit\u00e4ten sind die Brawijaya Universit\u00e4t, die UII, die Ahmad Dahlan Universit\u00e4t (UAD), die President Universit\u00e4t, die Semarang Staatsuniversit\u00e4t, die Padjajaran Universit\u00e4t und die STIE Malangkucecwara sowie die drei europ\u00e4ischen Universit\u00e4ten, die Universit\u00e4t von Gloucestershire, England, die Universit\u00e4t Granada Spanien und die International School for Social and Business Studies Slowenien. Die Er\u00f6ffnungsrede der Veranstaltung hielten Dr. Irene Pedreira Romero, Direktorin f\u00fcr Projekte und internationale Vereinbarungen und Vertreterin des Rektors der Universit\u00e4t Granada, Dr. Tjitjik<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,57],"tags":[],"class_list":["post-10263","post","type-post","status-publish","format-standard","category-evaluationsauftrag","category-ihilead"],"_links":{"self":[{"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/posts\/10263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/comments?post=10263"}],"version-history":[{"count":2,"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/posts\/10263\/revisions"}],"predecessor-version":[{"id":10403,"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/posts\/10263\/revisions\/10403"}],"wp:attachment":[{"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/media?parent=10263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/categories?post=10263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/tags?post=10263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}