{"id":10130,"date":"2023-03-09T11:49:14","date_gmt":"2023-03-09T10:49:14","guid":{"rendered":"https:\/\/isob-regensburg.net\/?p=10130"},"modified":"2024-02-26T11:52:09","modified_gmt":"2024-02-26T10:52:09","slug":"epale-community-story-2","status":"publish","type":"post","link":"https:\/\/isob-regensburg.net\/en\/projekt\/epale-community-story-2\/","title":{"rendered":"EPALE Community Story"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Gemeinsam mit unserer Partnerin Sandra F\u00e9lix setzen wir aktuell das Erasmus+ Projekt XTEAM-FEM um, bei der eine Online-Community und kompetenzbildende Angebote zur Unterst\u00fctzung von weiblichem Unternehmertum in Portugal aufgebaut werden soll. Die im Rahmen des Projektes \u201cXTEAM-FEM\u201d angebotenen Schulungen zielen auf die Entwicklung grundlegender Soft Skills bei Frauen ab, um die gesunde und ausgewogene Lebens- und Arbeitsweise von Unternehmerinnen zu f\u00f6rdern. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit ihrem Kurs vermittelt Sandra F\u00e9lix eine Reihe von Werkzeugen, die Unternehmerinnen unterst\u00fctzen, mit den Herausforderungen des heutigen Marktes umzugehen. Grundlage f\u00fcr die Entwicklung des Kurses war die berufliche Erfahrung der Trainerin in den Bereichen Unternehmertum, Leadership und Teammanagement. Der Kurs profitiert auch von ihrer Erfahrung in der Arbeit mit Unternehmer:innen und F\u00fchrungskr\u00e4ften in den letzten 7 Jahren. Das Programm verwendet erprobte Strategien f\u00fcr die Entwicklung eines Growth Mindset und erm\u00f6glicht eine verbesserte Kommunikation mit dem Klienten in zwischenmenschlichen und interpersonellen Beziehungen, f\u00f6rdert ein gesteigertes Selbstbewusstsein, vermittelt eine Form des Managements, die eine Steigerung der Produktivit\u00e4t erm\u00f6glicht. Mehr Informationen auf dem\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/epale.ec.europa.eu\/pt\/blog\/sandra-felix-autoconfianca-e-como-desenvolve-la?fbclid=IwAR18F1WWRCn7P-r1E_KSCxFcQOU9KtN5ZPMqzYzIcS1m5-8JFE4eR3k0-pM\" target=\"_blank\">EPALE-Beitrag<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/isob-regensburg.net\/wp-content\/uploads\/2023\/05\/Sandra-Felix.png\" alt=\"\"\/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Gemeinsam mit unserer Partnerin Sandra F\u00e9lix setzen wir aktuell das Erasmus+ Projekt XTEAM-FEM um, bei der eine Online-Community und kompetenzbildende Angebote zur Unterst\u00fctzung von weiblichem Unternehmertum in Portugal aufgebaut werden soll. Die im Rahmen des Projektes \u201cXTEAM-FEM\u201d angebotenen Schulungen zielen auf die Entwicklung grundlegender Soft Skills bei Frauen ab, um die gesunde und ausgewogene Lebens- und Arbeitsweise von Unternehmerinnen zu f\u00f6rdern. Mit ihrem Kurs vermittelt Sandra F\u00e9lix eine Reihe von Werkzeugen, die Unternehmerinnen unterst\u00fctzen, mit den Herausforderungen des heutigen Marktes umzugehen. Grundlage f\u00fcr die Entwicklung des Kurses war die berufliche Erfahrung der Trainerin in den Bereichen Unternehmertum, Leadership und Teammanagement. Der Kurs profitiert auch von ihrer Erfahrung in der Arbeit mit Unternehmer:innen und F\u00fchrungskr\u00e4ften in den letzten 7 Jahren. Das Programm verwendet erprobte Strategien f\u00fcr die Entwicklung eines Growth Mindset und erm\u00f6glicht eine verbesserte Kommunikation mit dem Klienten in zwischenmenschlichen und interpersonellen Beziehungen, f\u00f6rdert ein gesteigertes Selbstbewusstsein, vermittelt eine Form<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,50],"tags":[],"class_list":["post-10130","post","type-post","status-publish","format-standard","category-projekt","category-xteam-fem"],"_links":{"self":[{"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/posts\/10130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/comments?post=10130"}],"version-history":[{"count":8,"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/posts\/10130\/revisions"}],"predecessor-version":[{"id":10427,"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/posts\/10130\/revisions\/10427"}],"wp:attachment":[{"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/media?parent=10130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/categories?post=10130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isob-regensburg.net\/en\/wp-json\/wp\/v2\/tags?post=10130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}